{"id":563,"date":"2024-10-02T09:04:46","date_gmt":"2024-10-02T09:04:46","guid":{"rendered":"https:\/\/tidestudio.com\/blog\/?p=563"},"modified":"2024-10-02T09:04:47","modified_gmt":"2024-10-02T09:04:47","slug":"pubblicazione-dm13-09-2024-nuova-proroga-al-dm-01-09-2024","status":"publish","type":"post","link":"https:\/\/tidestudio.com\/blog\/pubblicazione-dm13-09-2024-nuova-proroga-al-dm-01-09-2024\/","title":{"rendered":"Pubblicazione DM13\/09\/2024: Nuova proroga al DM 01\/09\/2024"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Sulla <a href=\"https:\/\/www.gazzettaufficiale.it\/eli\/gu\/2024\/09\/18\/219\/sg\/pdf\">GUI n.219 del 18\/09\/2024<\/a> \u00e8 stato pubblicato  il <a href=\"https:\/\/www.gazzettaufficiale.it\/atto\/serie_generale\/caricaDettaglioAtto\/originario?atto.dataPubblicazioneGazzetta=2024-09-18&amp;atto.codiceRedazionale=24A04853&amp;elenco30giorni=true\">DM13\/09\/2024<\/a> contenenti delle modifiche e delle proroghe al DM 01\/09\/2021:<em>&#8220;Criteri generali per il controllo e la manutenzione degli impianti, attrezzature ed altri sistemi di sicurezza antincendio, ai sensi dell&#8217;articolo 46, comma 3, lettera a), punto 3,del D.lgs 9\/04\/2008 n.81&#8221;<\/em>. ll comma 1-bis dell&#8217;art.6 del DM01\/09\/2021 contiene la proroga al 25\/09\/2025. Viene modificato Allegato NN in quattro punti: al punto1 comma 4, al punto 4 comma 4, al punto 5 comma 5 ed al punto 4 comma 8. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Fonte:<\/strong><a href=\"https:\/\/www.gazzettaufficiale.it\/home\">Gazzetta Ufficiale<\/a><br><strong>Download:<\/strong><a href=\"https:\/\/www.gazzettaufficiale.it\/gazzetta\/serie_generale\/caricaDettaglio?dataPubblicazioneGazzetta=2023-09-11&amp;numeroGazzetta=212&amp;elenco30giorni=true\">GUI n.212 del 11\/09\/2023<\/a><br><strong>Articoli correlati:<\/strong><br><a href=\"https:\/\/tidestudio.com\/blog\/wp-admin\/post.php?post=344&amp;action=edit\">DM 01\/09\/2021: Criteri generali per il controllo e la manutenzione degli impianti, attrezzature ed altri sistemi in ambito della sicurezza antincendio.<\/a><br><a href=\"https:\/\/tidestudio.com\/blog\/wp-admin\/post.php?post=440&amp;action=edit\">PROROGA e MODICHE previste a porzioni del DM 01\/09\/2021<\/a><br><a href=\"https:\/\/tidestudio.com\/blog\/wp-admin\/post.php?post=445&amp;action=edit\">DM 15\/09\/2022: Modifiche al DM 01\/09\/2022 e proroga all\u2019 Art.4.<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Sulla GUI n.219 del 18\/09\/2024 \u00e8 stato pubblicato il DM13\/09\/2024 contenenti delle modifiche e delle proroghe al DM 01\/09\/2021:&#8220;Criteri generali per il controllo e la manutenzione degli impianti, attrezzature ed altri sistemi di sicurezza antincendio, ai sensi dell&#8217;articolo 46, comma 3, lettera a), punto 3,del D.lgs 9\/04\/2008 n.81&#8221;. ll comma 1-bis dell&#8217;art.6 del DM01\/09\/2021 contiene [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"sns_share_botton_hide":"","vkExUnit_sns_title":"","_vk_print_noindex":"","sitemap_hide":"","_veu_custom_css":"","veu_display_promotion_alert":"common","vkexunit_cta_each_option":"","_lightning_design_setting":{"layout":"default"},"footnotes":""},"categories":[4],"tags":[21,24],"class_list":["post-563","post","type-post","status-publish","format-standard","hentry","category-normativa","tag-manutenzione-formazione-antincendio-sgsa","tag-normativa-antincendio-vvf"],"veu_head_title_object":{"title":"","add_site_title":""},"_links":{"self":[{"href":"https:\/\/tidestudio.com\/blog\/wp-json\/wp\/v2\/posts\/563","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tidestudio.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tidestudio.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tidestudio.com\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/tidestudio.com\/blog\/wp-json\/wp\/v2\/comments?post=563"}],"version-history":[{"count":1,"href":"https:\/\/tidestudio.com\/blog\/wp-json\/wp\/v2\/posts\/563\/revisions"}],"predecessor-version":[{"id":564,"href":"https:\/\/tidestudio.com\/blog\/wp-json\/wp\/v2\/posts\/563\/revisions\/564"}],"wp:attachment":[{"href":"https:\/\/tidestudio.com\/blog\/wp-json\/wp\/v2\/media?parent=563"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tidestudio.com\/blog\/wp-json\/wp\/v2\/categories?post=563"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tidestudio.com\/blog\/wp-json\/wp\/v2\/tags?post=563"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}